{"id":26157,"date":"2021-12-15T08:05:16","date_gmt":"2021-12-15T11:05:16","guid":{"rendered":"https:\/\/cnr.org.br\/site\/?p=26157"},"modified":"2021-12-15T08:05:16","modified_gmt":"2021-12-15T11:05:16","slug":"viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282","status":"publish","type":"post","link":"https:\/\/cnr.org.br\/site\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/","title":{"rendered":"Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><div><img src='https:\/\/ifttt.com\/images\/no_image_card.png' style='max-width:600px;' \/><\/p>\n<div>Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados https:\/\/ift.tt\/3pX54Y6<\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados https:\/\/ift.tt\/3pX54Y6<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[525],"tags":[747],"class_list":["post-26157","post","type-post","status-publish","format-standard","hentry","category-home","tag-ifttt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados - CNR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados - CNR\" \/>\n<meta property=\"og:description\" content=\"Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados https:\/\/ift.tt\/3pX54Y6\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/\" \/>\n<meta property=\"og:site_name\" content=\"CNR\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-15T11:05:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ifttt.com\/images\/no_image_card.png\" \/>\n<meta name=\"author\" content=\"Imprensa CNR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Imprensa CNR\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\\\/\"},\"author\":{\"name\":\"Imprensa CNR\",\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/#\\\/schema\\\/person\\\/1f46209cd8c9d3d9887a0765b64ca66b\"},\"headline\":\"Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados\",\"datePublished\":\"2021-12-15T11:05:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\\\/\"},\"wordCount\":29,\"publisher\":{\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ifttt.com\\\/images\\\/no_image_card.png\",\"keywords\":[\"IFTTT\"],\"articleSection\":[\"Home\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\\\/\",\"url\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\\\/\",\"name\":\"Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados - CNR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ifttt.com\\\/images\\\/no_image_card.png\",\"datePublished\":\"2021-12-15T11:05:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ifttt.com\\\/images\\\/no_image_card.png\",\"contentUrl\":\"https:\\\/\\\/ifttt.com\\\/images\\\/no_image_card.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cnr.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/#website\",\"url\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/\",\"name\":\"CNR\",\"description\":\"Confedera\u00e7\u00e3o Nacional de Not\u00e1rios e Registradores\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/#organization\",\"name\":\"CNR\",\"url\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnr.org.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo_CNR_completa_colorida_2024.png\",\"contentUrl\":\"https:\\\/\\\/cnr.org.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo_CNR_completa_colorida_2024.png\",\"width\":910,\"height\":450,\"caption\":\"CNR\"},\"image\":{\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cnr.org.br\\\/novoportal\\\/#\\\/schema\\\/person\\\/1f46209cd8c9d3d9887a0765b64ca66b\",\"name\":\"Imprensa CNR\",\"sameAs\":[\"https:\\\/\\\/cnr.org.br\\\/site\"],\"url\":\"https:\\\/\\\/cnr.org.br\\\/site\\\/author\\\/imprensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados - CNR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/","og_locale":"pt_BR","og_type":"article","og_title":"Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados - CNR","og_description":"Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados https:\/\/ift.tt\/3pX54Y6","og_url":"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/","og_site_name":"CNR","article_published_time":"2021-12-15T11:05:16+00:00","og_image":[{"url":"https:\/\/ifttt.com\/images\/no_image_card.png","type":"","width":"","height":""}],"author":"Imprensa CNR","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Imprensa CNR"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/#article","isPartOf":{"@id":"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/"},"author":{"name":"Imprensa CNR","@id":"https:\/\/cnr.org.br\/novoportal\/#\/schema\/person\/1f46209cd8c9d3d9887a0765b64ca66b"},"headline":"Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados","datePublished":"2021-12-15T11:05:16+00:00","mainEntityOfPage":{"@id":"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/"},"wordCount":29,"publisher":{"@id":"https:\/\/cnr.org.br\/novoportal\/#organization"},"image":{"@id":"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/#primaryimage"},"thumbnailUrl":"https:\/\/ifttt.com\/images\/no_image_card.png","keywords":["IFTTT"],"articleSection":["Home"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/","url":"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/","name":"Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados - CNR","isPartOf":{"@id":"https:\/\/cnr.org.br\/novoportal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/#primaryimage"},"image":{"@id":"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/#primaryimage"},"thumbnailUrl":"https:\/\/ifttt.com\/images\/no_image_card.png","datePublished":"2021-12-15T11:05:16+00:00","breadcrumb":{"@id":"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/#primaryimage","url":"https:\/\/ifttt.com\/images\/no_image_card.png","contentUrl":"https:\/\/ifttt.com\/images\/no_image_card.png"},{"@type":"BreadcrumbList","@id":"https:\/\/cnr.org.br\/novoportal\/viagens-de-criancas-e-adolescentes-confira-cuidados-que-devem-ser-tomados-282\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cnr.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Viagens de crian\u00e7as e adolescentes: confira cuidados que devem ser tomados"}]},{"@type":"WebSite","@id":"https:\/\/cnr.org.br\/novoportal\/#website","url":"https:\/\/cnr.org.br\/novoportal\/","name":"CNR","description":"Confedera\u00e7\u00e3o Nacional de Not\u00e1rios e Registradores","publisher":{"@id":"https:\/\/cnr.org.br\/novoportal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnr.org.br\/novoportal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cnr.org.br\/novoportal\/#organization","name":"CNR","url":"https:\/\/cnr.org.br\/novoportal\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cnr.org.br\/novoportal\/#\/schema\/logo\/image\/","url":"https:\/\/cnr.org.br\/site\/wp-content\/uploads\/2026\/02\/Logo_CNR_completa_colorida_2024.png","contentUrl":"https:\/\/cnr.org.br\/site\/wp-content\/uploads\/2026\/02\/Logo_CNR_completa_colorida_2024.png","width":910,"height":450,"caption":"CNR"},"image":{"@id":"https:\/\/cnr.org.br\/novoportal\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cnr.org.br\/novoportal\/#\/schema\/person\/1f46209cd8c9d3d9887a0765b64ca66b","name":"Imprensa CNR","sameAs":["https:\/\/cnr.org.br\/site"],"url":"https:\/\/cnr.org.br\/site\/author\/imprensa\/"}]}},"_links":{"self":[{"href":"https:\/\/cnr.org.br\/site\/wp-json\/wp\/v2\/posts\/26157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnr.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnr.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnr.org.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cnr.org.br\/site\/wp-json\/wp\/v2\/comments?post=26157"}],"version-history":[{"count":0,"href":"https:\/\/cnr.org.br\/site\/wp-json\/wp\/v2\/posts\/26157\/revisions"}],"wp:attachment":[{"href":"https:\/\/cnr.org.br\/site\/wp-json\/wp\/v2\/media?parent=26157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnr.org.br\/site\/wp-json\/wp\/v2\/categories?post=26157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cnr.org.br\/site\/wp-json\/wp\/v2\/tags?post=26157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}